{"id":2116,"date":"2017-08-11T15:10:36","date_gmt":"2017-08-11T08:10:36","guid":{"rendered":"http:\/\/icao.telkomuniversity.ac.id\/?p=2116"},"modified":"2017-08-11T15:11:28","modified_gmt":"2017-08-11T08:11:28","slug":"leaders-talk","status":"publish","type":"post","link":"https:\/\/icao.telkomuniversity.ac.id\/en\/leaders-talk\/","title":{"rendered":"Leaders Talk"},"content":{"rendered":"<p>[do_widget id=ai1ec_agenda_widget-3]<br \/>\n[do_widget calendar]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[do_widget id=ai1ec_agenda_widget-3] [do_widget calendar]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_memberships_contains_paid_content":false,"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2116","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"gutentor_comment":0,"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/posts\/2116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/comments?post=2116"}],"version-history":[{"count":0,"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/posts\/2116\/revisions"}],"wp:attachment":[{"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/media?parent=2116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/categories?post=2116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icao.telkomuniversity.ac.id\/en\/wp-json\/wp\/v2\/tags?post=2116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}